{"id":49432,"date":"2026-06-19T09:41:31","date_gmt":"2026-06-19T08:41:31","guid":{"rendered":"https:\/\/agoraveszprem.hu\/termek\/"},"modified":"2026-07-14T17:01:40","modified_gmt":"2026-07-14T16:01:40","slug":"kolyokmozi-berlet-2026-07-16","status":"publish","type":"product","link":"https:\/\/agoraveszprem.hu\/eng\/product\/kolyokmozi-berlet-2026-07-16\/","title":{"rendered":"Sz\u00fcnidei K\u00f6ly\u00f6kmozi B\u00c9RLET \u00c9rv\u00e9nyes: 2026. 07. 16- 08. 13-ig"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-49434\" src=\"https:\/\/agoraveszprem.hu\/wp-content\/uploads\/2026\/06\/Berlet-teglalapalaku.jpg\" alt=\"\" width=\"1200\" height=\"628\" srcset=\"https:\/\/agoraveszprem.hu\/wp-content\/uploads\/2026\/06\/Berlet-teglalapalaku.jpg 1200w, https:\/\/agoraveszprem.hu\/wp-content\/uploads\/2026\/06\/Berlet-teglalapalaku-980x513.jpg 980w, https:\/\/agoraveszprem.hu\/wp-content\/uploads\/2026\/06\/Berlet-teglalapalaku-480x251.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_title et_pb_post_title_1_tb_body et_pb_bg_layout_light et_pb_text_align_left\">\n<div class=\"et_pb_title_container\"><\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_title et_pb_post_title_1_tb_body et_pb_bg_layout_light et_pb_text_align_left\">\n<div class=\"et_pb_title_container\"><\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_title et_pb_post_title_1_tb_body et_pb_bg_layout_light et_pb_text_align_left\">\n<div class=\"et_pb_title_container\">\n<h1 class=\"entry-title\" data-wahfont=\"32\">Sz\u00fcnidei K\u00f6ly\u00f6kmozi B\u00c9RLET<\/h1>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p data-wahfont=\"16\">Ez a b\u00e9rlet a <strong>Sz\u00fcnidei K\u00f6ly\u00f6kmozi <\/strong>h\u00e1rom vet\u00edt\u00e9s\u00e9re \u00e9rv\u00e9nyes.<\/p>\n<p data-wahfont=\"16\">2026.07.16. Toy Story 5.<\/p>\n<p data-wahfont=\"16\">2026.07.30. Mumbu Jumbo hatalmas kalandja<\/p>\n<p data-wahfont=\"16\">2026.08.13. Rufus, a legb\u00e1trabb tengeri sz\u00f6rny<\/p>\n<\/div>\n<\/div>\n<p data-wahfont=\"16\">B\u00e9rlet \u00e1r: 3000 Ft<\/p>\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p class=\"wp-block-paragraph\" data-wahfont=\"16\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>2026. j\u00falius 16.- 2026. augusztus 13-ig<\/p>\n<p>Online vagy helysz\u00edni b\u00e9rlet\u00e1r: 3000 Ft<\/p>\n<p>Reservations are made on a first-come, first-served basis.<\/p>","protected":false},"featured_media":49433,"template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<img class=\"wp-image-17890 aligncenter\" src=\"https:\/\/agoraveszprem.hu\/wp-content\/uploads\/2024\/04\/ferfi-hajomakettet-tart-a-kezeben-300x171.jpg\" alt=\"\" width=\"504\" height=\"287\" \/>\r\n\r\n\u00a0\r\n\r\nSv\u00e1jci-d\u00e1n v\u00edgj\u00e1t\u00e9k eredeti nyelven magyar felirattal, 92 perc, 2022<br class=\"html-br\" \/>Rendezte: Barbara Kulcsar<br class=\"html-br\" \/>Szerepl\u0151k: Esther Gemsch, Stefan Kurt, Ueli J\u00e4ggi, Gundi Ellert\r\n\r\nAz Arany\u00e9veink c\u00edm\u0171 sv\u00e1jci v\u00edgj\u00e1t\u00e9k egy frissen nyugd\u00edjba vonul\u00f3 h\u00e1zasp\u00e1r \u00fajrakezd\u00e9s\u00e9nek t\u00f6rt\u00e9net\u00e9t dolgozza fel, b\u00e1jos humorral, m\u00e9ly egy\u00fctt\u00e9rz\u00e9ssel, k\u00f6nnyeds\u00e9ge ellen\u00e9re is fontos, mindannyiunkat \u00e9rint\u0151 k\u00e9rd\u00e9sekkel. A magyar sz\u00e1rmaz\u00e1s\u00fa sv\u00e1jci rendez\u0151, Barbara Kulcsar filmje Sv\u00e1jcban k\u00f6z\u00f6ns\u00e9gkedvenc volt, de a n\u00e9met n\u00e9z\u0151k sz\u00edv\u00e9t is megh\u00f3d\u00edtotta. (JUNO11)\r\n\r\nKorhat\u00e1r: 16 \u00e9v\r\nBel\u00e9p\u0151d\u00edj: 1300 Ft","_et_gb_content_width":""},"product_brand":[],"product_cat":[39],"product_tag":[],"class_list":["post-49432","product","type-product","status-publish","has-post-thumbnail","product_cat-eticket","first","instock","virtual","taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/product\/49432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/media\/49433"}],"wp:attachment":[{"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/media?parent=49432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/product_brand?post=49432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/product_cat?post=49432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/agoraveszprem.hu\/eng\/wp-json\/wp\/v2\/product_tag?post=49432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}